{"id":6277,"date":"2018-09-25T17:22:24","date_gmt":"2018-09-25T15:22:24","guid":{"rendered":"https:\/\/www.gleichcom.samuraidev.ch\/?product=schwerhoerigen-telefon-amplidect-295-2-duo-geemarc"},"modified":"1000-01-01T00:00:00","modified_gmt":"1000-01-01T00:00:00","slug":"schwerhoerigen-telefon-amplidect-295-2-duo-geemarc","status":"publish","type":"product","link":"https:\/\/www.gleichcom.samuraidev.ch\/it\/shop\/schwerhoerigen-telefon-amplidect-295-2-duo-geemarc\/","title":{"rendered":"AmpliDECT 295-2 DUO Geemarc telefono con problemi di udito"},"content":{"rendered":"<div>\n\t<span style=\"color:#000000;\"><span style=\"font-size:16px;\"><strong>AmpliDECT 295-2 DUO Geemarc telefono con problemi di udito<\/strong><\/span><\/span>\n<\/div>\n<div>\n\t<br \/>\n\t<span style=\"color:#000000;\"><strong>Telefono per anziani<\/strong><br \/>\n\tA volte hai difficolt\u00e0 a capire al telefono la persona con cui stai parlando? I telefoni in commercio sono troppo complicati e confusi? Allora AmpliDECT 295-2 DUO potrebbe essere la soluzione che fa per voi. Il telefono cordless ha un volume regolabile fino a 30dB, \u00e8 compatibile con gli apparecchi acustici e ha una pratica funzione vivavoce. Inoltre, il portatile \u00e8 sempre comodamente in mano grazie al design ergonomico. Il display LCD \u00e8 extra large e ha una retroilluminazione integrata di facile lettura. Inoltre, i pulsanti larghi e un font extra large rendono il telefono facile da usare. Il telefono viene fornito con un ulteriore telefono cordless (portatile).<\/p>\n<p>\t<strong>Segreteria telefonica integrata<\/strong><br \/>\n\tAmpliDECT 295-2 DUO ha una segreteria telefonica integrata che pu\u00f2 registrare fino a 15 minuti. \u00c8 possibile ascoltare comodamente i messaggi memorizzati tramite richiesta remota e cancellare singoli messaggi o tutti i messaggi secondo necessit\u00e0. Inoltre, il display mostra sempre il numero di messaggi non letti &#8211; in modo da avere sempre una visione d&#8217;insieme!<\/p>\n<p>\t<strong>In sintesi<\/strong><\/span>\n<\/div>\n<ul>\n<li><span style=\"color:#000000;\">\u00a0\u00a0\u00a0 Telefono cordless rinforzato<\/span><\/li>\n<li><span style=\"color:#000000;\">\u00a0\u00a0\u00a0 Funzionamento semplice<\/span><\/li>\n<li><span style=\"color:#000000;\">\u00a0\u00a0\u00a0 Il volume del portatile \u00e8 aumentato di 30 dB<\/span><\/li>\n<li><span style=\"color:#000000;\">\u00a0 \u00a0 Melodie extra rumorose: fino a 75 dB sul ricevitore e 80 dB sull&#8217;unit\u00e0 bassi<\/span><\/li>\n<li><span style=\"color:#000000;\">\u00a0 \u00a0 funzione vivavoce<\/span><\/li>\n<li><span style=\"color:#000000;\">\u00a0\u00a0\u00a0 Elenco telefonico: 50 voci<\/span><\/li>\n<li><span style=\"color:#000000;\">\u00a0\u00a0\u00a0 Ricomposizione degli ultimi 10 numeri composti<\/span><\/li>\n<li><span style=\"color:#000000;\">\u00a0\u00a0\u00a0 funzione mute<\/span><\/li>\n<li><span style=\"color:#000000;\">\u00a0\u00a0\u00a0 5 suonerie polifoniche e 5 suonerie normali<\/span><\/li>\n<li><span style=\"color:#000000;\">\u00a0\u00a0\u00a0 Microtelefono ergonomico<\/span><\/li>\n<li><span style=\"color:#000000;\">\u00a0\u00a0\u00a0 Tasti extra larghi<\/span><\/li>\n<li><span style=\"color:#000000;\">\u00a0\u00a0\u00a0 tono dei tasti<\/span><\/li>\n<li><span style=\"color:#000000;\">\u00a0\u00a0\u00a0 Funzionamento con un massimo di 5 portatili aggiuntivi per base possibile<\/span><\/li>\n<li><span style=\"color:#000000;\">\u00a0\u00a0\u00a0 4 giorni in standby<\/span><\/li>\n<li><span style=\"color:#000000;\">\u00a0\u00a0\u00a0 Tempo di conversazione continua: 8 ore<\/span><\/li>\n<li><span style=\"color:#000000;\"><strong>\u00a0\u00a0\u00a0 Display LCD:<\/strong><\/span><\/li>\n<li><span style=\"color:#000000;\">\u00a0\u00a0\u00a0 Retroilluminazione bianca<\/span><\/li>\n<li><span style=\"color:#000000;\">\u00a0\u00a0\u00a0 Dimensione carattere 7 mm<\/span><\/li>\n<li><span style=\"color:#000000;\">\u00a0\u00a0\u00a0 Dimensioni: 40&#215;40 mm<\/span><\/li>\n<li><span style=\"color:#000000;\">\u00a0\u00a0\u00a0 7 lingue selezionabili: Inglese, tedesco, francese, italiano, olandese, spagnolo e russo<\/span><\/li>\n<li><span style=\"color:#000000;\"><strong>\u00a0\u00a0\u00a0 Segreteria telefonica integrata:<\/strong><\/span><\/li>\n<li><span style=\"color:#000000;\">\u00a0\u00a0\u00a0 15 minuti di registrazione<\/span><\/li>\n<li><span style=\"color:#000000;\">\u00a0\u00a0\u00a0 Visualizzazione di messaggi non letti<\/span><\/li>\n<li><span style=\"color:#000000;\">\u00a0\u00a0\u00a0 inchiesta a distanza<\/span><\/li>\n<li><span style=\"color:#000000;\">\u00a0\u00a0\u00a0 Eliminazione di messaggi singoli\/tutti i messaggi<\/span><\/li>\n<\/ul>\n<div>\n\t<br \/>\n\t<span style=\"color:#000000;\"><strong>Dotazione di fornitura<\/strong><\/span>\n<\/div>\n<ul>\n<li><span style=\"color:#000000;\">\u00a0\u00a0\u00a0 1 x telefono cordless (portatile)<\/span><\/li>\n<li><span style=\"color:#000000;\">\u00a0\u00a0\u00a0 1 x AmpliDECT 295 portatile<\/span><\/li>\n<li><span style=\"color:#000000;\">\u00a0\u00a0\u00a0 1 x stazione base<\/span><\/li>\n<li><span style=\"color:#000000;\">\u00a0\u00a0\u00a0 1 x adattatore di rete<\/span><\/li>\n<li><span style=\"color:#000000;\">\u00a0\u00a0\u00a0 2 x pacco batterie NiMH 2.4V 500 mA<\/span><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>AmpliDECT 295-2 DUO cordless, telefono senior rinforzato con microtelefono aggiuntivo. Segreteria telefonica inclusa. Compatibile con apparecchi acustici.<\/p>\n","protected":false},"featured_media":6272,"template":"","meta":{"inline_featured_image":false,"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}}},"product_brand":[],"product_cat":[2988],"product_tag":[],"class_list":{"0":"post-6277","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-telefono-per-anziani-it","7":"desktop-align-center","8":"tablet-align-center","9":"mobile-align-center","10":"ast-product-gallery-layout-horizontal-slider","11":"ast-product-tabs-layout-accordion","13":"first","14":"outofstock","15":"taxable","16":"shipping-taxable","17":"purchasable","18":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>AmpliDECT 295-2 DUO Geemarc telefono con problemi di udito im Onlineshop | Gleichcom AG<\/title>\n<meta name=\"description\" content=\"\u2705 AmpliDECT 295-2 DUO cordless, telefono senior rinforzato con microtelefono aggiuntivo. Segreteria telefonica inclusa. Compatibile con apparecchi acustici.\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AmpliDECT 295-2 DUO Geemarc telefono con problemi di udito im Onlineshop | Gleichcom AG\" \/>\n<meta property=\"og:description\" content=\"\u2705 AmpliDECT 295-2 DUO cordless, telefono senior rinforzato con microtelefono aggiuntivo. Segreteria telefonica inclusa. Compatibile con apparecchi acustici.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.gleichcom.samuraidev.ch\/it\/shop\/schwerhoerigen-telefon-amplidect-295-2-duo-geemarc\/\" \/>\n<meta property=\"og:site_name\" content=\"Gleichcom AG\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=100068749126981\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.gleichcom.samuraidev.ch\/wp-content\/uploads\/2023\/09\/AMPLIDECT295DUO_11.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"332\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.gleichcom.samuraidev.ch\\\/it\\\/shop\\\/schwerhoerigen-telefon-amplidect-295-2-duo-geemarc\\\/\",\"url\":\"https:\\\/\\\/www.gleichcom.samuraidev.ch\\\/it\\\/shop\\\/schwerhoerigen-telefon-amplidect-295-2-duo-geemarc\\\/\",\"name\":\"AmpliDECT 295-2 DUO Geemarc telefono con problemi di udito im Onlineshop | Gleichcom AG\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.gleichcom.samuraidev.ch\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.gleichcom.samuraidev.ch\\\/it\\\/shop\\\/schwerhoerigen-telefon-amplidect-295-2-duo-geemarc\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.gleichcom.samuraidev.ch\\\/it\\\/shop\\\/schwerhoerigen-telefon-amplidect-295-2-duo-geemarc\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.gleichcom.samuraidev.ch\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/AMPLIDECT295DUO_11.jpg\",\"datePublished\":\"2018-09-25T15:22:24+00:00\",\"description\":\"\u2705 AmpliDECT 295-2 DUO cordless, telefono senior rinforzato con microtelefono aggiuntivo. Segreteria telefonica inclusa. Compatibile con apparecchi acustici.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.gleichcom.samuraidev.ch\\\/it\\\/shop\\\/schwerhoerigen-telefon-amplidect-295-2-duo-geemarc\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.gleichcom.samuraidev.ch\\\/it\\\/shop\\\/schwerhoerigen-telefon-amplidect-295-2-duo-geemarc\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.gleichcom.samuraidev.ch\\\/it\\\/shop\\\/schwerhoerigen-telefon-amplidect-295-2-duo-geemarc\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.gleichcom.samuraidev.ch\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/AMPLIDECT295DUO_11.jpg\",\"contentUrl\":\"https:\\\/\\\/www.gleichcom.samuraidev.ch\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/AMPLIDECT295DUO_11.jpg\",\"width\":500,\"height\":332},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.gleichcom.samuraidev.ch\\\/it\\\/shop\\\/schwerhoerigen-telefon-amplidect-295-2-duo-geemarc\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.gleichcom.samuraidev.ch\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/www.gleichcom.samuraidev.ch\\\/it\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"AmpliDECT 295-2 DUO Geemarc telefono con problemi di udito\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.gleichcom.samuraidev.ch\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.gleichcom.samuraidev.ch\\\/it\\\/\",\"name\":\"Gleichcom AG\",\"description\":\"besser h\u00f6ren. besser sehen. besser leben.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.gleichcom.samuraidev.ch\\\/it\\\/#organization\"},\"alternateName\":\"Gleichcom\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.gleichcom.samuraidev.ch\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.gleichcom.samuraidev.ch\\\/it\\\/#organization\",\"name\":\"Gleichcom AG\",\"alternateName\":\"Gleichcom\",\"url\":\"https:\\\/\\\/www.gleichcom.samuraidev.ch\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.gleichcom.samuraidev.ch\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.gleichcom.samuraidev.ch\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/gleichcom-ag-logo-quadrat-farbig-mitte@696.png\",\"contentUrl\":\"https:\\\/\\\/www.gleichcom.samuraidev.ch\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/gleichcom-ag-logo-quadrat-farbig-mitte@696.png\",\"width\":437,\"height\":437,\"caption\":\"Gleichcom AG\"},\"image\":{\"@id\":\"https:\\\/\\\/www.gleichcom.samuraidev.ch\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=100068749126981\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AmpliDECT 295-2 DUO Geemarc telefono con problemi di udito im Onlineshop | Gleichcom AG","description":"\u2705 AmpliDECT 295-2 DUO cordless, telefono senior rinforzato con microtelefono aggiuntivo. Segreteria telefonica inclusa. Compatibile con apparecchi acustici.","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"it_IT","og_type":"article","og_title":"AmpliDECT 295-2 DUO Geemarc telefono con problemi di udito im Onlineshop | Gleichcom AG","og_description":"\u2705 AmpliDECT 295-2 DUO cordless, telefono senior rinforzato con microtelefono aggiuntivo. Segreteria telefonica inclusa. Compatibile con apparecchi acustici.","og_url":"https:\/\/www.gleichcom.samuraidev.ch\/it\/shop\/schwerhoerigen-telefon-amplidect-295-2-duo-geemarc\/","og_site_name":"Gleichcom AG","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=100068749126981","og_image":[{"width":500,"height":332,"url":"https:\/\/www.gleichcom.samuraidev.ch\/wp-content\/uploads\/2023\/09\/AMPLIDECT295DUO_11.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.gleichcom.samuraidev.ch\/it\/shop\/schwerhoerigen-telefon-amplidect-295-2-duo-geemarc\/","url":"https:\/\/www.gleichcom.samuraidev.ch\/it\/shop\/schwerhoerigen-telefon-amplidect-295-2-duo-geemarc\/","name":"AmpliDECT 295-2 DUO Geemarc telefono con problemi di udito im Onlineshop | Gleichcom AG","isPartOf":{"@id":"https:\/\/www.gleichcom.samuraidev.ch\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.gleichcom.samuraidev.ch\/it\/shop\/schwerhoerigen-telefon-amplidect-295-2-duo-geemarc\/#primaryimage"},"image":{"@id":"https:\/\/www.gleichcom.samuraidev.ch\/it\/shop\/schwerhoerigen-telefon-amplidect-295-2-duo-geemarc\/#primaryimage"},"thumbnailUrl":"https:\/\/www.gleichcom.samuraidev.ch\/wp-content\/uploads\/2023\/09\/AMPLIDECT295DUO_11.jpg","datePublished":"2018-09-25T15:22:24+00:00","description":"\u2705 AmpliDECT 295-2 DUO cordless, telefono senior rinforzato con microtelefono aggiuntivo. Segreteria telefonica inclusa. Compatibile con apparecchi acustici.","breadcrumb":{"@id":"https:\/\/www.gleichcom.samuraidev.ch\/it\/shop\/schwerhoerigen-telefon-amplidect-295-2-duo-geemarc\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.gleichcom.samuraidev.ch\/it\/shop\/schwerhoerigen-telefon-amplidect-295-2-duo-geemarc\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.gleichcom.samuraidev.ch\/it\/shop\/schwerhoerigen-telefon-amplidect-295-2-duo-geemarc\/#primaryimage","url":"https:\/\/www.gleichcom.samuraidev.ch\/wp-content\/uploads\/2023\/09\/AMPLIDECT295DUO_11.jpg","contentUrl":"https:\/\/www.gleichcom.samuraidev.ch\/wp-content\/uploads\/2023\/09\/AMPLIDECT295DUO_11.jpg","width":500,"height":332},{"@type":"BreadcrumbList","@id":"https:\/\/www.gleichcom.samuraidev.ch\/it\/shop\/schwerhoerigen-telefon-amplidect-295-2-duo-geemarc\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.gleichcom.samuraidev.ch\/it\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.gleichcom.samuraidev.ch\/it\/shop\/"},{"@type":"ListItem","position":3,"name":"AmpliDECT 295-2 DUO Geemarc telefono con problemi di udito"}]},{"@type":"WebSite","@id":"https:\/\/www.gleichcom.samuraidev.ch\/it\/#website","url":"https:\/\/www.gleichcom.samuraidev.ch\/it\/","name":"Gleichcom AG","description":"besser h\u00f6ren. besser sehen. besser leben.","publisher":{"@id":"https:\/\/www.gleichcom.samuraidev.ch\/it\/#organization"},"alternateName":"Gleichcom","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.gleichcom.samuraidev.ch\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.gleichcom.samuraidev.ch\/it\/#organization","name":"Gleichcom AG","alternateName":"Gleichcom","url":"https:\/\/www.gleichcom.samuraidev.ch\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.gleichcom.samuraidev.ch\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.gleichcom.samuraidev.ch\/wp-content\/uploads\/2023\/09\/gleichcom-ag-logo-quadrat-farbig-mitte@696.png","contentUrl":"https:\/\/www.gleichcom.samuraidev.ch\/wp-content\/uploads\/2023\/09\/gleichcom-ag-logo-quadrat-farbig-mitte@696.png","width":437,"height":437,"caption":"Gleichcom AG"},"image":{"@id":"https:\/\/www.gleichcom.samuraidev.ch\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=100068749126981"]}]}},"uagb_featured_image_src":{"full":["https:\/\/www.gleichcom.samuraidev.ch\/wp-content\/uploads\/2023\/09\/AMPLIDECT295DUO_11.jpg",500,332,false],"thumbnail":["https:\/\/www.gleichcom.samuraidev.ch\/wp-content\/uploads\/2023\/09\/AMPLIDECT295DUO_11.jpg",150,100,false],"medium":["https:\/\/www.gleichcom.samuraidev.ch\/wp-content\/uploads\/2023\/09\/AMPLIDECT295DUO_11.jpg",300,199,false],"medium_large":["https:\/\/www.gleichcom.samuraidev.ch\/wp-content\/uploads\/2023\/09\/AMPLIDECT295DUO_11.jpg",500,332,false],"large":["https:\/\/www.gleichcom.samuraidev.ch\/wp-content\/uploads\/2023\/09\/AMPLIDECT295DUO_11.jpg",500,332,false],"1536x1536":["https:\/\/www.gleichcom.samuraidev.ch\/wp-content\/uploads\/2023\/09\/AMPLIDECT295DUO_11.jpg",500,332,false],"2048x2048":["https:\/\/www.gleichcom.samuraidev.ch\/wp-content\/uploads\/2023\/09\/AMPLIDECT295DUO_11.jpg",500,332,false],"woocommerce_thumbnail":["https:\/\/www.gleichcom.samuraidev.ch\/wp-content\/uploads\/2023\/09\/AMPLIDECT295DUO_11.jpg",300,199,false],"woocommerce_single":["https:\/\/www.gleichcom.samuraidev.ch\/wp-content\/uploads\/2023\/09\/AMPLIDECT295DUO_11.jpg",500,332,false],"woocommerce_gallery_thumbnail":["https:\/\/www.gleichcom.samuraidev.ch\/wp-content\/uploads\/2023\/09\/AMPLIDECT295DUO_11-100x100.jpg",100,100,true]},"uagb_author_info":{"display_name":"","author_link":"https:\/\/www.gleichcom.samuraidev.ch\/it\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"AmpliDECT 295-2 DUO cordless, telefono senior rinforzato con microtelefono aggiuntivo. Segreteria telefonica inclusa. Compatibile con apparecchi acustici.","_links":{"self":[{"href":"https:\/\/www.gleichcom.samuraidev.ch\/it\/wp-json\/wp\/v2\/product\/6277","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.gleichcom.samuraidev.ch\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.gleichcom.samuraidev.ch\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.gleichcom.samuraidev.ch\/it\/wp-json\/wp\/v2\/media\/6272"}],"wp:attachment":[{"href":"https:\/\/www.gleichcom.samuraidev.ch\/it\/wp-json\/wp\/v2\/media?parent=6277"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.gleichcom.samuraidev.ch\/it\/wp-json\/wp\/v2\/product_brand?post=6277"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.gleichcom.samuraidev.ch\/it\/wp-json\/wp\/v2\/product_cat?post=6277"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.gleichcom.samuraidev.ch\/it\/wp-json\/wp\/v2\/product_tag?post=6277"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}